{"id":5422,"date":"2024-09-30T23:54:21","date_gmt":"2024-09-30T21:54:21","guid":{"rendered":"https:\/\/www.wg-west.de\/?p=5422"},"modified":"2024-10-01T00:12:32","modified_gmt":"2024-09-30T22:12:32","slug":"nachhaltige-woche","status":"publish","type":"post","link":"https:\/\/www.wg-west.de\/de_ls\/2024\/09\/30\/nachhaltige-woche\/","title":{"rendered":"Nachhaltige Woche"},"content":{"rendered":"<div id=\"fws_6a97d81de4c59\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p style=\"text-align: left;\"><strong>&#8222;Nachhaltige Woche&#8220; am WG West<\/strong><\/p>\n<p style=\"text-align: left;\">Nachhaltigkeit ist f\u00fcr uns als Fairtrade-Schule nicht nur ein Schlagwort, sondern wird auch gelebt:<\/p>\n<p style=\"text-align: left;\">In der Woche vom<span style=\"color: #ff0000;\"> 7. Oktober bis 11. Oktober<\/span> findet die erste &#8222;Nachhaltige Woche&#8220; am WG West statt. Jeden Tag in dieser Woche gibt es dazu verschiedene Aktionen. N\u00e4here Infos findet ihr auf dem folgenden Flyer.<\/p>\n<p style=\"text-align: left;\"><em>(Text und Flyer: Johannes von Kalckreuth)<\/em><\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d81de5c8b\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"img-with-aniamtion-wrap  custom-size\" data-max-width=\"100%\" data-max-width-mobile=\"default\" data-shadow=\"none\" data-animation=\"none\" >\n      <div class=\"inner\">\n        <div class=\"hover-wrap\"> \n          <div class=\"hover-wrap-inner\">\n            <a href=\"https:\/\/www.wg-west.de\/cms\/wp-content\/uploads\/2024\/09\/Nachhaltige_Woche_am_WG-_West_Flyer.jpg\" class=\"pp\">\n              <img loading=\"lazy\" decoding=\"async\" class=\"img-with-animation skip-lazy\" data-delay=\"0\" height=\"1024\" width=\"768\" data-animation=\"none\" src=\"https:\/\/www.wg-west.de\/cms\/wp-content\/uploads\/2024\/09\/Nachhaltige_Woche_am_WG-_West_Flyer-768x1024.jpg\" alt=\"\" srcset=\"https:\/\/www.wg-west.de\/cms\/wp-content\/uploads\/2024\/09\/Nachhaltige_Woche_am_WG-_West_Flyer-768x1024.jpg 768w, https:\/\/www.wg-west.de\/cms\/wp-content\/uploads\/2024\/09\/Nachhaltige_Woche_am_WG-_West_Flyer-225x300.jpg 225w, https:\/\/www.wg-west.de\/cms\/wp-content\/uploads\/2024\/09\/Nachhaltige_Woche_am_WG-_West_Flyer-9x12.jpg 9w, https:\/\/www.wg-west.de\/cms\/wp-content\/uploads\/2024\/09\/Nachhaltige_Woche_am_WG-_West_Flyer.jpg 1125w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/>\n            <\/a>\n          <\/div>\n        <\/div>\n         \n      <\/div>\n      <\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d81de73ae\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"margin-top: 20px; height: 1px; margin-bottom: 20px;\" data-width=\"100%\" data-animate=\"\" data-animation-delay=\"\" data-color=\"default\" class=\"divider-border\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d81de7d03\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p style=\"text-align: left;\">Mit Klick auf den folgenden Button kann der Flyer als pdf-Dokument heruntergeladen werden.<\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a97d81de8595\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<a class=\"nectar-button medium regular extra-color-2 has-icon  regular-button\"  role=\"button\" style=\"\"  href=\"https:\/\/www.wg-west.de\/cms\/wp-content\/uploads\/2024\/09\/Die-Nachhaltige-Woche-am-WG-West_flyer.pdf\" data-color-override=\"false\" data-hover-color-override=\"false\" data-hover-text-color-override=\"#fff\"><span>Download Flyer<\/span><i  class=\"fa fa-folder-open\"><\/i><\/a>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"\"Nachhaltige Woche\" am WG West Nachhaltigkeit ist f\u00fcr uns als Fairtrade-Schule nicht nur ein Schlagwort, sondern wird auch gelebt: In der Woche vom 7. Oktober bis 11. Oktober findet die...","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[608],"class_list":["post-5422","post","type-post","status-publish","format-standard","category-allgemein","tag-faire-woche"],"_links":{"self":[{"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/posts\/5422","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/comments?post=5422"}],"version-history":[{"count":7,"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/posts\/5422\/revisions"}],"predecessor-version":[{"id":5432,"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/posts\/5422\/revisions\/5432"}],"wp:attachment":[{"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/media?parent=5422"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/categories?post=5422"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.wg-west.de\/de_ls\/wp-json\/wp\/v2\/tags?post=5422"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}